{"id":22012,"date":"2025-04-04T23:19:50","date_gmt":"2025-04-04T21:19:50","guid":{"rendered":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1.png"},"modified":"2025-04-08T16:35:00","modified_gmt":"2025-04-08T14:35:00","slug":"modifiche-circolazione-treni1-2","status":"inherit","type":"attachment","link":"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/","title":{"rendered":"Train Service Modifications"},"author":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Train Service Modifications &raquo; Cinque Terre Consorzio Turistico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Train Service Modifications &raquo; Cinque Terre Consorzio Turistico\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Cinque Terre Consorzio Turistico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/consorziocinqueterre\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T14:35:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1.png\" \/>\n\t<meta property=\"og:image:alt\" content=\"Train Service Modifications\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"571\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.cinqueterre.it\/fr\/#organization\",\"name\":\"Consorzio Turistico Cinque Terre\",\"url\":\"https:\/\/www.cinqueterre.it\/fr\/\",\"sameAs\":[\"https:\/\/www.facebook.com\/consorziocinqueterre\/\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.cinqueterre.it\/fr\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2024\/07\/consorzio-turistico-cinque-terre.jpg\",\"contentUrl\":\"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2024\/07\/consorzio-turistico-cinque-terre.jpg\",\"width\":295,\"height\":109,\"caption\":\"Consorzio Turistico Cinque Terre\"},\"image\":{\"@id\":\"https:\/\/www.cinqueterre.it\/fr\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cinqueterre.it\/fr\/#website\",\"url\":\"https:\/\/www.cinqueterre.it\/fr\/\",\"name\":\"Cinque Terre Consorzio Turistico\",\"description\":\"Tutte le informazioni per vivere il territorio\",\"publisher\":{\"@id\":\"https:\/\/www.cinqueterre.it\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.cinqueterre.it\/fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/#webpage\",\"url\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/\",\"name\":\"Train Service Modifications &raquo; Cinque Terre Consorzio Turistico\",\"isPartOf\":{\"@id\":\"https:\/\/www.cinqueterre.it\/fr\/#website\"},\"datePublished\":\"2025-04-04T21:19:50+00:00\",\"dateModified\":\"2025-04-08T14:35:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cinqueterre.it\/pt-br\/\",\"url\":\"https:\/\/www.cinqueterre.it\/pt-br\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/04\/modifiche-circolazione-treni\/\",\"url\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/04\/modifiche-circolazione-treni\/\",\"name\":\"Train Service Modifications\"}},{\"@type\":\"ListItem\",\"position\":3,\"item\":{\"@id\":\"https:\/\/www.cinqueterre.it\/pt-br\/2025\/04\/05\/train-service-modifications\/modifiche-circolazione-treni1-2\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","description":{"rendered":"<p class=\"attachment\"><a data-rel=\"iLightbox[postimages]\" data-title=\"\" data-caption=\"\" href='https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1.png'><img width=\"300\" height=\"214\" src=\"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-300x214.png\" class=\"attachment-medium size-medium\" alt=\"Train Service Modifications\" srcset=\"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-200x143.png 200w, https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-300x214.png 300w, https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-400x286.png 400w, https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-600x428.png 600w, https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-768x548.png 768w, https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1.png 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"Train Service Modifications","media_type":"image","mime_type":"image\/png","media_details":{"width":800,"height":571,"file":"2025\/04\/Modifiche-circolazione-treni1.png","sizes":{"medium":{"file":"Modifiche-circolazione-treni1-300x214.png","width":300,"height":214,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-300x214.png"},"thumbnail":{"file":"Modifiche-circolazione-treni1-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-150x150.png"},"medium_large":{"file":"Modifiche-circolazione-treni1-768x548.png","width":768,"height":548,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-768x548.png"},"blog-large":{"file":"Modifiche-circolazione-treni1-669x272.png","width":669,"height":272,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-669x272.png"},"blog-medium":{"file":"Modifiche-circolazione-treni1-320x202.png","width":320,"height":202,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-320x202.png"},"recent-posts":{"file":"Modifiche-circolazione-treni1-700x441.png","width":700,"height":441,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-700x441.png"},"recent-works-thumbnail":{"file":"Modifiche-circolazione-treni1-66x66.png","width":66,"height":66,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-66x66.png"},"fusion-200":{"file":"Modifiche-circolazione-treni1-200x143.png","width":200,"height":143,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-200x143.png"},"fusion-400":{"file":"Modifiche-circolazione-treni1-400x286.png","width":400,"height":286,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-400x286.png"},"fusion-600":{"file":"Modifiche-circolazione-treni1-600x428.png","width":600,"height":428,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-600x428.png"},"portfolio-full":{"file":"Modifiche-circolazione-treni1-800x400.png","width":800,"height":400,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-800x400.png"},"portfolio-one":{"file":"Modifiche-circolazione-treni1-540x272.png","width":540,"height":272,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-540x272.png"},"portfolio-two":{"file":"Modifiche-circolazione-treni1-460x295.png","width":460,"height":295,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-460x295.png"},"portfolio-three":{"file":"Modifiche-circolazione-treni1-300x214.png","width":300,"height":214,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-300x214.png"},"portfolio-five":{"file":"Modifiche-circolazione-treni1-177x142.png","width":177,"height":142,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1-177x142.png"},"full":{"file":"Modifiche-circolazione-treni1.png","width":800,"height":571,"mime_type":"image\/png","source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":22029,"source_url":"https:\/\/www.cinqueterre.it\/wp-content\/uploads\/2025\/04\/Modifiche-circolazione-treni1.png","_links":{"self":[{"href":"https:\/\/www.cinqueterre.it\/pt-br\/wp-json\/wp\/v2\/media\/22012"}],"collection":[{"href":"https:\/\/www.cinqueterre.it\/pt-br\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.cinqueterre.it\/pt-br\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.cinqueterre.it\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cinqueterre.it\/pt-br\/wp-json\/wp\/v2\/comments?post=22012"}]}}